{"id":2498,"date":"2019-01-23T16:22:24","date_gmt":"2019-01-23T16:22:24","guid":{"rendered":"https:\/\/grupramonet.com\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/"},"modified":"2019-01-23T16:22:24","modified_gmt":"2019-01-23T16:22:24","slug":"se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto","status":"publish","type":"post","link":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/","title":{"rendered":"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto"},"content":{"rendered":"<p><span style=\"color: #000000; font-family: Calibri;\">Ya s\u00e9 lo que me vais a decir, que menuda americanada, que si est\u00e1s enamorado lo tienes que demostrar en el d\u00eda a d\u00eda no s\u00f3lo el 14 de febrero, que es una celebraci\u00f3n creada para consumir\u2026 S\u00ed, ten\u00e9is raz\u00f3n. Pero, tambi\u00e9n soy de los que creo que bastantes d\u00edas tenemos llenos de malas noticias, \u00bfno?&#8230; No es tan malo dedicarle 24 horas al AMOR en may\u00fasculas\u2026 y ya, c\u00f3mo lo celebra cada uno o c\u00f3mo le pone el toque personal, eso ya es otra cosa. Se puede celebrar San Valent\u00edn con una notita de amor por la ma\u00f1ana o un momento compartido viendo Netflix en el sof\u00e1 de casa \u00bfno?<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">A m\u00ed, que ya sab\u00e9is que me encanta saber de d\u00f3nde vienen las celebraciones y las tradiciones he investigado, tambi\u00e9n esta vez para ver de d\u00f3nde ha salido este Santo y por qu\u00e9 celebramos un d\u00eda dedicado al amor con su nombre y la respuesta, la verdad, me ha sorprendido. <\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">En principio cre\u00eda que era una festividad pagana que se hab\u00edan inventado los grandes centros comerciales pero lo cierto es que es una festividad cristiana. Se celebra en conmemoraci\u00f3n de las obras realizadas por San Valent\u00edn de Roma. San Valent\u00edn casaba a soldados con sus damas en las bodegas de las c\u00e1rceles en los tiempos en los que Claudio II prohibi\u00f3 el cristianismo en el Imperio romano. Cuando Claudio se enter\u00f3 de las pr\u00e1cticas \u201cilegales\u201d que estaba llevando a cabo Valent\u00edn lo mand\u00f3 llamar, en principio s\u00f3lo para aleccionarlo, pero, influido por sus altos cargos, acab\u00f3 decapit\u00e1ndolo. <\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">As\u00ed que \u00e9sta es la historia, \u00bfno os parece curiosa? Lo cierto es que yo s\u00ed que creo que San Valent\u00edn tiene su qu\u00e9 y en el Grup Ramonet tambi\u00e9n lo piensan, as\u00ed que para celebrarlo, sortean una cena para dos en El Nou Ramonet valorada en 90 euros. Para participar s\u00f3lo ten\u00e9is que seguir el perfil de @ramonetdelabarceloneta en Instagram y etiquetar en los comentarios del post a la persona con la que os gustar\u00eda compartir esa cena. \u00a1El 14 de febrero conoceremos el ganador@! <\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\">Venga, animaos\u2026 regalar a vuestra pareja una cena para dos que no olvide nunca. Yo, ya he participado <\/span><span style=\"margin: 0px; font-family: 'Segoe UI Emoji',sans-serif;\">\ud83d\ude09<\/span><span style=\"font-family: Calibri;\">\u00a0 <\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\">Aqu\u00ed ten\u00e9is las bases lesgales del sorteo :\u00a0<a href=\"https:\/\/elnouramonet.com\/bases-legales-2\/\">https:\/\/elnouramonet.com\/bases-legales-2\/<\/a><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya s\u00e9 lo que me vais a decir, que menuda americanada, que si est\u00e1s enamorado lo tienes que demostrar en el d\u00eda a d\u00eda no s\u00f3lo el 14 de febrero,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[81,82,83,84,85],"class_list":["post-2498","post","type-post","status-publish","format-standard","has-post-thumbnail","category-festividades-en","tag-barceloneta-en","tag-can-ramonet-en","tag-el-nou-ramonet-en","tag-grup-ramonet-en","tag-ramonet-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto - Grup Ramonet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto - Grup Ramonet\" \/>\n<meta property=\"og:description\" content=\"Ya s\u00e9 lo que me vais a decir, que menuda americanada, que si est\u00e1s enamorado lo tienes que demostrar en el d\u00eda a d\u00eda no s\u00f3lo el 14 de febrero,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/\" \/>\n<meta property=\"og:site_name\" content=\"Grup Ramonet\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-23T16:22:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupramonet.com\/wp-content\/uploads\/2024\/02\/logogrup-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"elfresco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elfresco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/\"},\"author\":{\"name\":\"elfresco\",\"@id\":\"https:\/\/grupramonet.com\/en\/#\/schema\/person\/d31a6ebb02f108d326aab7452b2a1551\"},\"headline\":\"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto\",\"datePublished\":\"2019-01-23T16:22:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\/\/grupramonet.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg\",\"keywords\":[\"Barceloneta\",\"Can Ramonet\",\"El Nou Ramonet\",\"Grup ramonet\",\"Ramonet\"],\"articleSection\":[\"Festividades\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/\",\"url\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/\",\"name\":\"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto - Grup Ramonet\",\"isPartOf\":{\"@id\":\"https:\/\/grupramonet.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg\",\"datePublished\":\"2019-01-23T16:22:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage\",\"url\":\"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg\",\"contentUrl\":\"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg\",\"width\":2095,\"height\":2560,\"caption\":\"Sorteo El nou Ramonet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/grupramonet.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/grupramonet.com\/en\/#website\",\"url\":\"https:\/\/grupramonet.com\/en\/\",\"name\":\"Grup Ramonet Barceloneta\",\"description\":\"Tradici\u00f3 i sabor, des del cor de la Barceloneta.\",\"publisher\":{\"@id\":\"https:\/\/grupramonet.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/grupramonet.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/grupramonet.com\/en\/#organization\",\"name\":\"Grup Ramonet Barceloneta\",\"url\":\"https:\/\/grupramonet.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/grupramonet.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/grupramonet.com\/wp-content\/uploads\/2024\/04\/grup-ramonet-jpg.webp\",\"contentUrl\":\"https:\/\/grupramonet.com\/wp-content\/uploads\/2024\/04\/grup-ramonet-jpg.webp\",\"width\":696,\"height\":696,\"caption\":\"Grup Ramonet Barceloneta\"},\"image\":{\"@id\":\"https:\/\/grupramonet.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/elnouramonet\/\",\"https:\/\/www.instagram.com\/canramonetbcn\/\",\"https:\/\/www.instagram.com\/ramonetdelabarceloneta\/\",\"https:\/\/www.instagram.com\/lavinotecadelabarceloneta\/\",\"https:\/\/www.instagram.com\/lafresca_barceloneta\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/grupramonet.com\/en\/#\/schema\/person\/d31a6ebb02f108d326aab7452b2a1551\",\"name\":\"elfresco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/grupramonet.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8c10285a0291100878bbf899a69296a0406f6e9ad306da031826db6abbbe6c25?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8c10285a0291100878bbf899a69296a0406f6e9ad306da031826db6abbbe6c25?s=96&d=mm&r=g\",\"caption\":\"elfresco\"},\"sameAs\":[\"https:\/\/grupramonet.com\"],\"url\":\"https:\/\/grupramonet.com\/en\/author\/elfresco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto - Grup Ramonet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/","og_locale":"en_US","og_type":"article","og_title":"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto - Grup Ramonet","og_description":"Ya s\u00e9 lo que me vais a decir, que menuda americanada, que si est\u00e1s enamorado lo tienes que demostrar en el d\u00eda a d\u00eda no s\u00f3lo el 14 de febrero,...","og_url":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/","og_site_name":"Grup Ramonet","article_published_time":"2019-01-23T16:22:24+00:00","og_image":[{"width":400,"height":500,"url":"https:\/\/grupramonet.com\/wp-content\/uploads\/2024\/02\/logogrup-3.png","type":"image\/png"}],"author":"elfresco","twitter_card":"summary_large_image","twitter_misc":{"Written by":"elfresco","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#article","isPartOf":{"@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/"},"author":{"name":"elfresco","@id":"https:\/\/grupramonet.com\/en\/#\/schema\/person\/d31a6ebb02f108d326aab7452b2a1551"},"headline":"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto","datePublished":"2019-01-23T16:22:24+00:00","mainEntityOfPage":{"@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/"},"wordCount":420,"publisher":{"@id":"https:\/\/grupramonet.com\/en\/#organization"},"image":{"@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage"},"thumbnailUrl":"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg","keywords":["Barceloneta","Can Ramonet","El Nou Ramonet","Grup ramonet","Ramonet"],"articleSection":["Festividades"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/","url":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/","name":"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto - Grup Ramonet","isPartOf":{"@id":"https:\/\/grupramonet.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage"},"image":{"@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage"},"thumbnailUrl":"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg","datePublished":"2019-01-23T16:22:24+00:00","breadcrumb":{"@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#primaryimage","url":"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg","contentUrl":"https:\/\/grupramonet.com\/wp-content\/uploads\/2019\/01\/sorteo_san_valentin-scaled.jpg","width":2095,"height":2560,"caption":"Sorteo El nou Ramonet"},{"@type":"BreadcrumbList","@id":"https:\/\/grupramonet.com\/en\/se-acerca-san-valentin-y-lo-vamos-a-celebrar-por-todo-lo-alto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/grupramonet.com\/en\/"},{"@type":"ListItem","position":2,"name":"San Valent\u00edn ya est\u00e1 aqu\u00ed y lo vamos a celebrar por todo lo alto"}]},{"@type":"WebSite","@id":"https:\/\/grupramonet.com\/en\/#website","url":"https:\/\/grupramonet.com\/en\/","name":"Grup Ramonet Barceloneta","description":"Tradici\u00f3 i sabor, des del cor de la Barceloneta.","publisher":{"@id":"https:\/\/grupramonet.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupramonet.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/grupramonet.com\/en\/#organization","name":"Grup Ramonet Barceloneta","url":"https:\/\/grupramonet.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/grupramonet.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/grupramonet.com\/wp-content\/uploads\/2024\/04\/grup-ramonet-jpg.webp","contentUrl":"https:\/\/grupramonet.com\/wp-content\/uploads\/2024\/04\/grup-ramonet-jpg.webp","width":696,"height":696,"caption":"Grup Ramonet Barceloneta"},"image":{"@id":"https:\/\/grupramonet.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/elnouramonet\/","https:\/\/www.instagram.com\/canramonetbcn\/","https:\/\/www.instagram.com\/ramonetdelabarceloneta\/","https:\/\/www.instagram.com\/lavinotecadelabarceloneta\/","https:\/\/www.instagram.com\/lafresca_barceloneta\/"]},{"@type":"Person","@id":"https:\/\/grupramonet.com\/en\/#\/schema\/person\/d31a6ebb02f108d326aab7452b2a1551","name":"elfresco","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/grupramonet.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8c10285a0291100878bbf899a69296a0406f6e9ad306da031826db6abbbe6c25?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c10285a0291100878bbf899a69296a0406f6e9ad306da031826db6abbbe6c25?s=96&d=mm&r=g","caption":"elfresco"},"sameAs":["https:\/\/grupramonet.com"],"url":"https:\/\/grupramonet.com\/en\/author\/elfresco\/"}]}},"_links":{"self":[{"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/posts\/2498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/comments?post=2498"}],"version-history":[{"count":0,"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/posts\/2498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/media\/1191"}],"wp:attachment":[{"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/media?parent=2498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/categories?post=2498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupramonet.com\/en\/wp-json\/wp\/v2\/tags?post=2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}